{"id":10627,"date":"2020-07-10T11:57:16","date_gmt":"2020-07-10T15:57:16","guid":{"rendered":"http:\/\/kciphilanthropy.flywheelsites.com\/?p=10627"},"modified":"2020-07-28T09:25:40","modified_gmt":"2020-07-28T13:25:40","slug":"oser-reinventer-la-collecte-de-fonds","status":"publish","type":"post","link":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/","title":{"rendered":"Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; module_class=\u00a0\u00bbtrends-background\u00a0\u00bb _builder_version=\u00a0\u00bb4.5.0&Prime; background_color=\u00a0\u00bb#333f48&Prime; background_image=\u00a0\u00bbhttps:\/\/kciphilanthropy.com\/wp-content\/uploads\/2020\/07\/Big-Rethink-Hero-Image.jpg\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px|\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|\u00a0\u00bb][et_pb_row module_class=\u00a0\u00bbarrow-row\u00a0\u00bb _builder_version=\u00a0\u00bb3.25&Prime; width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px|||\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|\u00a0\u00bb make_fullwidth=\u00a0\u00bbon\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb0px||0px|\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_code admin_label=\u00a0\u00bbBack Button\u00a0\u00bb module_class=\u00a0\u00bbpeople-back\u00a0\u00bb _builder_version=\u00a0\u00bb3.17.6&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb]<a href=\"\/fr\/insights\">Back<\/a>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb module_class=\u00a0\u00bbtrends-header\u00a0\u00bb _builder_version=\u00a0\u00bb3.25&Prime; max_width=\u00a0\u00bb1210px\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px|\u00a0\u00bb custom_padding=\u00a0\u00bb360px||0px|\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb160px||0px|\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb custom_width_px=\u00a0\u00bb1210px\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb3.25&Prime; background_color=\u00a0\u00bb#ffffff\u00a0\u00bb custom_padding=\u00a0\u00bb20px|||50px\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbHeading\u00a0\u00bb module_class=\u00a0\u00bbtrends-heading\u00a0\u00bb _builder_version=\u00a0\u00bb4.5.1&Prime; custom_margin=\u00a0\u00bb||20px|\u00a0\u00bb]<\/p>\n<h1><strong>Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19 \u200b<\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; specialty=\u00a0\u00bbon\u00a0\u00bb module_class=\u00a0\u00bbtrends-content\u00a0\u00bb _builder_version=\u00a0\u00bb3.22&Prime; inner_width=\u00a0\u00bb60%\u00a0\u00bb inner_max_width=\u00a0\u00bb60%\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb60%\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_4&Prime; specialty_columns=\u00a0\u00bb3&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_row_inner admin_label=\u00a0\u00bbRow\u00a0\u00bb _builder_version=\u00a0\u00bb3.25&Prime;][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_post_title title=\u00a0\u00bboff\u00a0\u00bb author=\u00a0\u00bboff\u00a0\u00bb date_format=\u00a0\u00bbM Y\u00a0\u00bb categories=\u00a0\u00bboff\u00a0\u00bb comments=\u00a0\u00bboff\u00a0\u00bb featured_image=\u00a0\u00bboff\u00a0\u00bb admin_label=\u00a0\u00bbDate &#8211; don&rsquo;t edit\u00a0\u00bb module_class=\u00a0\u00bbtrends-date\u00a0\u00bb _builder_version=\u00a0\u00bb3.17.2&Prime;][\/et_pb_post_title][et_pb_text _builder_version=\u00a0\u00bb4.5.1&Prime;]<\/p>\n<p>In\u00e9dit. Inconnu. Incertain.<\/p>\n<p>Ce ne sont l\u00e0 que quelques-uns des mots utilis\u00e9s pour d\u00e9crire la conjoncture dans laquelle nous nous trouvons alors que nous devons composer avec la pand\u00e9mie de la COVID-19 et ses r\u00e9percussions. Et, compte tenu du degr\u00e9 d\u2019incertitude auquel nous sommes confront\u00e9s, il est difficile de savoir quel en sera l\u2019impact sur les organismes caritatifs canadiens et leur collecte de fonds.<\/p>\n<p>Les organismes doivent faire preuve de d\u00e9termination dans la planification de leur redressement ainsi que des mesures qui les placeront sur la voie de la croissance. Maintenant que la poussi\u00e8re commence \u00e0 retomber et que nous continuons notre lente \u00e9mergence de cette pand\u00e9mie, il est imp\u00e9ratif que les conseils d\u2019administration et les \u00e9quipes de direction am\u00e8nent leurs organismes \u00e0 initier des exercices de planification et d\u2019articulation de la vision.<\/p>\n<p>Dans ce rapport, nous avons tent\u00e9 de cr\u00e9er un \u00ab\u00a0guichet unique\u00a0\u00bb que vous pourrez utiliser au cours des prochains mois pour orienter vos activit\u00e9s de planification. Nous y avons rassembl\u00e9 le meilleur de nos r\u00e9flexions sur l\u2019impact qu\u2019aura la pand\u00e9mie sur la collecte de fonds et la philanthropie et identifi\u00e9 des \u00e9l\u00e9ments sp\u00e9cifiques qui devraient faire l\u2019objet d\u2019un examen de la part des organismes. Nous y offrons aussi conseils et orientation sur des domaines au-del\u00e0 de la collecte de fonds que les organismes devraient examiner afin d\u2019assurer leur croissance future. Enfin, nous y offrons des liens \u00e0 diverses ressources qui pourraient s\u2019av\u00e9rer utiles \u00e0 votre travail de r\u00e9flexion et \u00e0 vos discussions au cours des mois \u00e0 venir.\u00a0 \u00a0<\/p>\n<p>Trois grandes orientations\u00a0:<\/p>\n<p>Premi\u00e8rement, ne pas planifier n\u2019est pas une option. Peu importe que vous ayez ou n\u2019ayez pas \u00e9t\u00e9 touch\u00e9s de fa\u00e7on significative par cette pand\u00e9mie, votre organisme ne peut se permettre de conclure que votre fa\u00e7on de faire les choses par le pass\u00e9 restera efficace \u00e0 l\u2019avenir. Comme la reprise sera l\u00e9g\u00e8rement diff\u00e9rente pour chaque organisme, il faut \u00e9viter les formules g\u00e9n\u00e9rales dans l\u2019\u00e9laboration de votre plan et de votre r\u00e9ponse ultime. Et n\u2019imaginez pas non plus qu\u2019une approche \u00ab\u00a0tout du premier coup\u00a0\u00bb conviendra. \u00c9tablissez des m\u00e9canismes, y compris des groupes de travail ou des comit\u00e9s au sein de votre conseil d\u2019administration et chez vos employ\u00e9s, qui vous permettront d\u2019examiner et de revoir vos d\u00e9cisions strat\u00e9giques sur une base continue au moins pour l\u2019ann\u00e9e \u00e0 venir. \u00a0<\/p>\n<p>Deuxi\u00e8mement, entretenez une \u00ab\u00a0culture du questionnement\u00a0\u00bb et impliquez les chefs de file chez vos b\u00e9n\u00e9voles et vos donateurs. La conjoncture exige un esprit ouvert dans votre travail de planification et un engagement renouvel\u00e9 de vos principales parties prenantes dans votre mission afin de bien saisir ce \u00e0 quoi ces gens pensent et ce \u00e0 quoi ils s\u2019attendent. Engagez-les par le biais de sondages, de conversations et de groupes de discussion. Sentant qu\u2019ils sont co-cr\u00e9ateurs de la voie que vous tracerez pour votre organisme, ils donneront plus d\u2019eux-m\u00eames, ce qui ne peut que vous rendre plus fort.<\/p>\n<p>Et enfin, ne restez pas sur pause trop longtemps\u2026 ou, pis encore, n\u2019arr\u00eatez pas carr\u00e9ment. Nous savons par exp\u00e9rience avec les ralentissements que ceux qui ont poursuivi leur travail et maintenu une certaine impulsion s\u2019en sont beaucoup mieux sortis, tandis que ceux qui ont pris un recul ont constat\u00e9 qu\u2019ils avaient perdu \u00e9norm\u00e9ment de terrain. Donc, qu\u2019il s\u2019agisse d\u2019une nouvelle initiative, d\u2019une campagne planifi\u00e9e ou d\u2019initiatives de collecte de fonds en cours, r\u00e9fl\u00e9chissez bien \u00e0 la fa\u00e7on dont vous irez de l\u2019avant, tout en vous assurant que votre organisme maintienne un certain \u00e9lan.\u00a0<\/p>\n<p><span style=\"color: #e56a54;\"><strong>REPENSER LES PROGRAMMES DE COLLECTE DE FONDS &#8211; SIX DOMAINES \u00c0 EXPLORER<\/strong><\/span><\/p>\n<p><strong> 1. Votre argumentaire : r\u00e9pondre aux int\u00e9r\u00eats changeants des donateurs<\/strong><\/p>\n<p>\u00c0 l\u2019avenir, la plupart des organismes devront prendre un virage et revoir leur argumentaire pour r\u00e9pondre \u00e0 une nouvelle r\u00e9alit\u00e9. Il pourrait devoir r\u00e9aliser un exercice complet d\u2019\u00e9tablissement des priorit\u00e9s de collecte de fonds, ou plus simplement ajuster certains \u00e9l\u00e9ments et peaufiner les messages. Dans cet exercice de r\u00e9flexion sur votre argumentaire, il serait bon de tenir compte des tendances et observations suivantes qui influenceront les int\u00e9r\u00eats des donateurs au cours des mois et possiblement des ann\u00e9es \u00e0 venir\u00a0:<\/p>\n<ul>\n<li>Un changement dans les priorit\u00e9s philanthropiques, y compris \u00ab\u00a0mettre l\u2019accent sur les besoins essentiels\u00a0\u00bb et \u00ab\u00a0aider \u00e0 la relance\u00a0\u00bb.<\/li>\n<li>Un d\u00e9sir de cibler encore plus sa propre collectivit\u00e9.<\/li>\n<li>Une ouverture \u00e0 comprendre l\u2019impact de cette crise sur l\u2019organisme, surtout de la part de ses donateurs les plus loyaux.<\/li>\n<li>L\u2019occasion de b\u00e2tir un argumentaire plus solide pour un soutien op\u00e9rationnel.<\/li>\n<li>La tr\u00e8s grande importance en ce moment des valeurs organisationnelles \u2013 les donateurs surveillent la fa\u00e7on dont les organismes r\u00e9pondent \u00e0 la crise.<\/li>\n<\/ul>\n<p>Liens ressources.<\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/bulletin-5-maintenir-son-elan-planifiez-vos-scenarios\/\">KCI Tendances &#8211; Planifiez vos sc\u00e9narios : Maintenir son \u00e9lan en p\u00e9riode d\u2019incertitude \u2013 Bulletin 5<\/a><\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/bulletin-6-maintenir-son-elan-votre-argumentaire\/\">Pr\u00e9sentez votre argumentaire :\u00a0Maintenir son \u00e9lan en p\u00e9riode d\u2019incertitude \u2013 Bulletin 6<\/a><\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/2014-bulletin-1-largumentaire\/\">L\u2019argumentaire \u2013 Tendances 2014<\/a><\/p>\n<p><strong>2. Donateurs individuels : renforcer les liens<\/strong><\/p>\n<p>Les dons individuels sont depuis longtemps, pour les organismes caritatifs, le levier le plus important et le plus r\u00e9silient des revenus de la philanthropie. On ne s\u2019attend pas \u00e0 ce que cette situation change. Ce qui pourrait changer toutefois est la fa\u00e7on dont les organismes s\u2019y prendront pour solliciter des dons aupr\u00e8s des individus. Ceux qui d\u00e9pendaient d\u2019une collecte de fonds transactionnelle et \u00e9v\u00e9nementielle auront vraisemblablement des difficult\u00e9s pour un certain temps, compte tenu des r\u00e9percussions psychologiques des mesures de distanciation et des cons\u00e9quences \u00e9conomiques de la pand\u00e9mie, y compris un taux de ch\u00f4mage \u00e9lev\u00e9. Il faudrait plut\u00f4t que les ressources et l\u2019attention ciblent les programmes de dons individuels qui permettent de b\u00e2tir et de renforcer les rapports personnels, en particulier avec les individus qui ont une plus grande capacit\u00e9 de donner. Tenez compte, entre autres, des tendances et observations suivantes\u00a0:<\/p>\n<ul>\n<li>Toujours une grande ouverture des donateurs majeurs d\u2019engager la conversation.<\/li>\n<li>Un int\u00e9r\u00eat accru pour la planification de legs, la mise sur pied de fonds de dotation et une r\u00e9vision des dispositions testamentaires.<\/li>\n<li>La cr\u00e9ation et la mise en \u0153uvre par l\u2019organisme d\u2019une capacit\u00e9 pour des dons majeurs, interm\u00e9diaires, mensuels et planifi\u00e9s.<\/li>\n<li>La conversion de nouveaux donateurs en contributeurs r\u00e9guliers gr\u00e2ce \u00e0 un solide processus d\u2019engagement et de fid\u00e9lisation.<\/li>\n<li>L\u2019importance de r\u00e9sister \u00e0 toute envie de sabrer dans les programmes de fid\u00e9lisation.<\/li>\n<\/ul>\n<p>Lien ressource.<\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/2014-bulletin-3-le-marketing-cible\/\">Le marketing cibl\u00e9 \u2013 Tendances 2014<\/a><\/p>\n<p><strong>3. Le num\u00e9rique : Accro\u00eetre (ou cr\u00e9er) une capacit\u00e9 num\u00e9rique <\/strong><\/p>\n<p>Les organismes qui avaient d\u00e9j\u00e0 une capacit\u00e9 num\u00e9rique ont \u00e9t\u00e9 en mesure de r\u00e9pondre beaucoup plus rapidement aux changements requis quand les mesures de distanciation ont \u00e9t\u00e9 mises en place. Lorsque vous r\u00e9fl\u00e9chirez \u00e0 la possibilit\u00e9 d\u2019accro\u00eetre votre capacit\u00e9 num\u00e9rique, tenez compte, entre autres, des tendances et observations suivantes\u00a0:<\/p>\n<ul>\n<li>Filtrez votre strat\u00e9gie num\u00e9rique \u00e0 travers trois lentilles\u00a0: l\u2019engagement, la collecte de fonds et la prise de d\u00e9cision fond\u00e9e sur les donn\u00e9es.<\/li>\n<li>La capacit\u00e9 num\u00e9rique implique la cr\u00e9ation d\u2019un paysage num\u00e9rique complet qui englobe votre site web, vos plateformes sociales, les approches par courriel, l\u2019optimisation des moteurs de recherche, la cr\u00e9ation de contenu, le marketing num\u00e9rique, les m\u00e9canismes d\u2019intervention ainsi que le suivi et l\u2019int\u00e9gration des donn\u00e9es.<\/li>\n<li>Les campagnes et les initiatives en ligne peuvent \u00eatre cr\u00e9\u00e9es en migrant les appels de contributions et les \u00e9v\u00e9nements actuels vers un format en ligne, ou en cr\u00e9ant une campagne en ligne sp\u00e9ciale.<\/li>\n<li>Il faut avoir la capacit\u00e9 organisationnelle de d\u00e9velopper, soutenir et r\u00e9aliser votre strat\u00e9gie, y compris\u00a0:\n<ul>\n<li>Les connaissances, les comp\u00e9tences et les aptitudes techniques des employ\u00e9s;<\/li>\n<li>L\u2019infrastructure, telle les syst\u00e8mes, les bases de donn\u00e9es et les plateformes;<\/li>\n<li>Les m\u00e9canismes pour surveiller et \u00e9valuer, dont l\u2019analytique et les outils de compte-rendu.<\/li>\n<\/ul>\n<\/li>\n<li>De bonnes pratiques en mati\u00e8re de gestion des donn\u00e9es sont un \u00e9l\u00e9ment fondamental de la mise en \u0153uvre d\u2019une strat\u00e9gie de collecte de fonds num\u00e9rique.<\/li>\n<\/ul>\n<p>Liens ressources.<\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/2018-bulletin-2-lavenir-est-numerique\/\">L\u2019avenir est num\u00e9rique \u2013 Tendances 2018 <\/a><\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/2016-bulletin-2-parlons-dinnovation\/\">Parlons d\u2019innovation &#8211; Tendances 2016<\/a><\/p>\n<p><strong>4. Programmes de collecte de fonds : assurer la diversit\u00e9 et la pertinence<\/strong><\/p>\n<p>Il est essentiel d\u2019\u00e9valuer la gamme enti\u00e8re de vos programmes de collecte de fonds pour identifier ceux qui demeurent solides et pertinents, ceux qui requi\u00e8rent investissements et innovations et ceux qui devraient \u00eatre \u00e9limin\u00e9s. Dans vos efforts pour trouver la bonne combinaison, tenez compte, entre autres, des \u00e9l\u00e9ments suivants\u00a0:<\/p>\n<ul>\n<li>Une bonne combinaison de programmes de collecte de fonds devrait inclure le recrutement, le renouvellement et la mise \u00e0 niveau.<\/li>\n<li>N\u2019abandonnez pas compl\u00e8tement vos canaux traditionnels, y compris vos programmes de publipostage, puisque certains donateurs pr\u00e9f\u00e9reront continuer de donner de cette fa\u00e7on.<\/li>\n<li>Examinez l\u2019ensemble de vos \u00e9v\u00e9nements, tant l\u2019aspect financier que la pertinence de chacun d\u2019entre eux pour engager, sensibiliser et fid\u00e9liser vos donateurs.<\/li>\n<li>Investissez dans votre capacit\u00e9 en mati\u00e8re de dons mensuels, interm\u00e9diaires, majeurs et planifi\u00e9s, tous des sources de revenu durables.<\/li>\n<li>Assurez-vous de fid\u00e9liser syst\u00e9matiquement vos donateurs pour minimiser le risque que des legs soient r\u00e9voqu\u00e9s ou que des engagements ne soient pas remplis.<\/li>\n<li>Une int\u00e9gration de la collecte de fonds ax\u00e9e sur les relations, notamment au niveau des dons majeurs et planifi\u00e9s, devient de plus en plus commune; on offre aux donateurs potentiels la possibilit\u00e9 de faire des dons combin\u00e9s qui comprennent un engagement actuel et futur.<\/li>\n<\/ul>\n<p>Lien resource.<\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/les-gens-de-la-collecte-de-fonds\/\">Les gens de la collecte de fonds \u2013 partie 1 &#8211; Tendances: Fev 2020<\/a><\/p>\n<p><strong>5. Partenariats avec le secteur priv\u00e9 : assurer sa pertinence<\/strong><\/p>\n<p>En ces temps de crise, les gens s\u2019int\u00e9ressent de pr\u00e8s \u00e0 la fa\u00e7on dont les compagnies r\u00e9pondent aux besoins de la collectivit\u00e9. Cette attente de la part des consommateurs ne s\u2019estompera pas et, par cons\u00e9quent, encore plus d\u2019entreprises vont r\u00e9fl\u00e9chir \u00e0 ce qu\u2019elles font pour le \u00ab\u00a0bien commun\u00a0\u00bb. Elles chercheront des solutions adapt\u00e9es aux besoins, un domaine o\u00f9 le secteur caritatif est pass\u00e9 ma\u00eetre. Dans vos r\u00e9flexions sur le potentiel des partenariats avec le secteur priv\u00e9, tenez compte, entre autres, des tendances et observations suivantes\u00a0:<\/p>\n<ul>\n<li>Les entreprises canadiennes ont intensifi\u00e9 leurs efforts de mani\u00e8re tr\u00e8s significative en offrant un soutien philanthropique durant la pand\u00e9mie.<\/li>\n<li>Pour les compagnies, la contribution sociale est vue comme une fa\u00e7on de diff\u00e9rencier leur marque. Ainsi, la cl\u00e9 pour r\u00e9aliser des partenariats avec le secteur priv\u00e9 sera de d\u00e9montrer comment un organisme caritatif peut aider \u00e0 l\u2019avancement de la strat\u00e9gie d\u2019entreprise et de la marque.<\/li>\n<li>Les compagnies int\u00e8grent de plus en plus leurs activit\u00e9s philanthropiques \u00e0 leur mod\u00e8le d\u2019affaires global; elles explorent comment leurs \u00e9quipes, leurs produits et leurs comp\u00e9tences de base peuvent r\u00e9pondre \u00e0 des besoins importants dans la collectivit\u00e9.<\/li>\n<li>Les entreprises cherchent \u00e0 d\u00e9velopper des partenariats personnalis\u00e9s qui incorporent leur mod\u00e8le d\u2019affaires et impliquent leur client\u00e8le et leurs employ\u00e9s. Il ne s\u2019agit plus seulement d\u2019\u00e9crire un ch\u00e8que \u00e0 un organisme caritatif.<\/li>\n<li>Les compagnies vont fort probablement proc\u00e9der \u00e0 un examen de leurs strat\u00e9gies d\u2019investissement dans la collectivit\u00e9, ce qui veut dire que les priorit\u00e9s en mati\u00e8re de dons et de partenariats pourraient fort bien changer ou \u00e9voluer.<\/li>\n<\/ul>\n<p>Lien ressource.<\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/savoir-faire\/\">Num\u00e9ro sp\u00e9cial \u2013 Dons COVID-19<\/a><\/p>\n<p><strong>6. Campagnes : Actualiser la strat\u00e9gie\u2026 et cr\u00e9er une raison<\/strong><\/p>\n<p>Postpand\u00e9mie, les campagnes continueront d\u2019\u00eatre un outil important de collecte de fonds pour les organismes caritatifs. Elles font en sorte que nous soyons dignes d\u2019attention et cr\u00e9ent un enthousiasme, un nouvel \u00e9lan et un sentiment d\u2019urgence. Elles rehaussent le profil et amplifie la voix. Dans vos r\u00e9flexions sur la pertinence strat\u00e9gique d\u2019une campagne, tenez compte, entre autres, des tendances et observations suivantes :<\/p>\n<ul>\n<li>Proc\u00e9dez \u00e0 un examen complet et \u00e0 une \u00e9valuation exhaustive de votre campagne actuelle pour d\u00e9terminer si vous devez faire pivoter certains \u00e9l\u00e9ments de votre strat\u00e9gie, de votre argumentaire, de votre structure de b\u00e9n\u00e9voles, de vos messages ou de vos \u00e9ch\u00e9anciers.<\/li>\n<li>Les campagnes ont besoin de pr\u00e9paration et de planification pour r\u00e9ussir; on ne peut pas simplement en lancer une sans avoir fait le travail n\u00e9cessaire.<\/li>\n<li>Consid\u00e9rez la campagne comme un moyen de faire progresser vos objectifs au-del\u00e0 des enjeux financiers, comme renforcer votre image, accro\u00eetre l\u2019engagement communautaire et promouvoir une culture philanthropique.<\/li>\n<li>Les b\u00e9n\u00e9voles sont un \u00e9l\u00e9ment crucial des campagnes. Ils donnent acc\u00e8s \u00e0 de nouveaux r\u00e9seaux et stimulent de nouvelles relations avec des philanthropes cl\u00e9s et des partenaires importants du secteur priv\u00e9, en plus de rehausser votre cr\u00e9dibilit\u00e9 par leur pr\u00e9sence.<\/li>\n<\/ul>\n<p>Lien ressource.<\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/campagnescollectedefonds\/\">KCI Tendances &#8211; Campagnes de collecte de fonds<\/a><\/p>\n<p><span style=\"color: #e56a54;\"><strong>OSER SE R\u00c9INVENTER AU-DEL\u00c0 DE LA COLLECTE DE FONDS<\/strong><\/span><\/p>\n<p>Planifier pour la r\u00e9ussite future de la collecte de fonds va au-del\u00e0 de la fonction de collecte en soi et doit inclure <strong>une r\u00e9flexion globale et un examen de votre organisme dans son ensemble \u2013 votre valeur, votre capacit\u00e9 et votre culture.<\/strong><\/p>\n<p><strong>Valeur\u00a0:<\/strong> En ces temps de changements et de bouleversements profonds, les organismes devraient entreprendre un examen rigoureux et courageux de leur raison d\u2019\u00eatre, de leur fa\u00e7on de travailler et de leurs op\u00e9rations. Ce travail exige de trouver des failles et de remettre en question les id\u00e9es re\u00e7ues \u00e0 propos de votre mission, de votre identit\u00e9 et de votre fa\u00e7on de travailler.<\/p>\n<p><strong>Capacit\u00e9\u00a0:<\/strong> Les organismes doivent travailler s\u00e9rieusement \u00e0 identifier et \u00e0 combler les lacunes dans leur capacit\u00e9 d\u2019ex\u00e9cuter. Et qui pense capacit\u00e9 doit s\u2019assurer d\u2019inclure les \u00e9l\u00e9ments suivants\u00a0: vos gens, votre savoir et vos connaissances, votre structure, votre infrastructure et votre gouvernance. Il sera sans doute n\u00e9cessaire d\u2019accro\u00eetre, d\u2019actualiser et de requalifier.<\/p>\n<p><strong>Culture\u00a0:<\/strong> L\u2019environnement en constante \u00e9volution dans lequel nous naviguons exige une culture organisationnelle qui soit hautement alerte et souple et qui repose principalement sur la capacit\u00e9 d\u2019adaptation des employ\u00e9s. Les cultures organisationnelles souples se caract\u00e9risent par une forte tol\u00e9rance de l\u2019ambigu\u00eft\u00e9, un esprit d\u2019entrepreneuriat, des \u00e9quipes et des employ\u00e9s habilit\u00e9s ainsi que des cycles acc\u00e9l\u00e9r\u00e9s d\u2019apprentissage et de prise de d\u00e9cision. Ces organisations habilitent v\u00e9ritablement leurs employ\u00e9s et les encouragent \u00e0 mettre de l\u2019avant de nouvelles id\u00e9es et des innovations.<\/p>\n<p>Liens ressources.<\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/2016-bulletin-1-garder-le-cap-economie-et-collecte-de-fonds\/\">Garder le cap (\u00c9conomie et collecte de fonds) \u2013 Tendances 2016<\/a><\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/fr\/2015-bulletin-2-changer-et-sadapter\/\">Changer et s\u2019adapter \u2013 Trends 2015<\/a><\/p>\n<p><span style=\"color: #e56a54;\"><strong>COMMENT NOUS POUVONS AIDER<\/strong><\/span><\/p>\n<p>G\u00e9rer les d\u00e9fis et les changements perturbateurs expos\u00e9s dans ce rapport exigera une discipline, une souplesse, un esprit critique et une gestion de projets rigoureuse. L\u2019\u00e9quipe d\u2019experts-conseils de KCI \u00e0 travers le Canada est l\u00e0 pour vous aider \u00e0 aller de l\u2019avant.<\/p>\n<p>Voici quelques-unes des fa\u00e7ons dont nous appuyons les organismes tout au long de la crise et comment nous le ferons pendant la p\u00e9riode de reprise qui suivra. Cela vient s\u2019ajouter \u00e0 la gamme permanente de services que nous offrons. Pour en savoir plus ou pour communiquer avec nous, vous pouvez nous \u00e9crire \u00e0 <a href=\"mailto:info@kciphilanthropie.com\">info@kciphilanthropie.com<\/a> ou consulter notre site web \u00e0 <a href=\"https:\/\/kciphilanthropy.com\/fr\/experience\/\">https:\/\/kciphilanthropy.com\/fr\/experience\/<\/a>.<\/p>\n<p><strong>Analyse de sc\u00e9narios et planification op\u00e9rationnelle<\/strong><\/p>\n<p>Ne pas planifier n\u2019est pas une option. Mais trouver le temps et l\u2019\u00e9nergie pour s\u2019engager dans un processus inclusif, strat\u00e9gique et centr\u00e9 sur les donn\u00e9es est difficile, et ce, m\u00eame dans les circonstances les plus favorables. KCI peut travailler avec vous pour engager vos principales parties prenantes, y compris les membres de votre conseil d\u2019administration, analyser votre situation actuelle et cr\u00e9er un espace qui permettra \u00e0 votre \u00e9quipe de r\u00e9aliser le travail strat\u00e9gique n\u00e9cessaire. Notre exp\u00e9rience, notre point de vue ind\u00e9pendant et notre solide vision p\u00e9riph\u00e9rique peuvent vous aider \u00e0 assurer que votre plan soit solide, adaptatif, et centr\u00e9 sur les domaines avantageux actuels et en \u00e9mergence.<\/p>\n<p><strong>D\u00e9velopper la capacit\u00e9 pour la collecte de fonds fond\u00e9e sur les relations avec les donateurs<\/strong><\/p>\n<p>Modifier vos programmes de collecte de fonds pour b\u00e2tir des relations durables avec vos donateurs individuels et les fid\u00e9liser est essentiel dans le contexte actuel. Mais ce n\u2019est pas toujours simple \u00e0 faire, surtout pour les organismes dont la force historique r\u00e9side dans des m\u00e9thodes de collecte de fonds transactionnelles et \u00e9v\u00e9nementielles. Fort de sa vaste expertise en collecte de fonds centr\u00e9e sur les donateurs, y compris les programmes de dons mensuels, interm\u00e9diaires et majeurs, KCI peut vous aider \u00e0 d\u00e9velopper votre capacit\u00e9 d\u2019entreprendre ce type de collecte de fonds en peaufinant votre argumentaire et vos propositions sur la valeur, en renfor\u00e7ant vos programmes, en augmentant votre bassin de donateurs potentiels, en formant vos employ\u00e9es ainsi qu\u2019en \u00e9laborant des indicateurs cl\u00e9s qui vous permettront de suivre vos progr\u00e8s et capitaliser sur ceux-ci.<\/p>\n<p><strong>Restructuration organisationnelle et aide \u00e0 la transition<\/strong><\/p>\n<p>Puisque les fa\u00e7ons dont nous engageons les gens qui nous appuient et g\u00e9n\u00e9rons des revenus \u00e9voluent rapidement, il est essentiel d\u2019assurer que vos ressources les plus importantes \u2013 vos gens \u2013 soient au diapason de votre strat\u00e9gie globale et de vos plans. KCI peut vous offrir une perspective et des comp\u00e9tences externes sur comment organiser, former et r\u00e9mun\u00e9rer vos gens de fa\u00e7on \u00e0 ce que votre \u00e9quipe et votre organisme dans son ensemble puissent atteindre leur plein potentiel. Plus pr\u00e9cis\u00e9ment, KCI peut vous aider \u00e0\u00a0:<\/p>\n<ul>\n<li>Adapter votre structure pour qu\u2019elle s\u2019aligne \u00e0 votre strat\u00e9gie et soit conforme aux normes sup\u00e9rieures en vigueur dans le secteur.<\/li>\n<li>Concevoir et fournir des plans de transition et de formation pour assurer que vos gens, tant vos employ\u00e9s que vos b\u00e9n\u00e9voles, puissent assumer de nouveaux r\u00f4les avec en mains les outils et les comp\u00e9tences n\u00e9cessaires \u00e0 leur r\u00e9ussite.<\/li>\n<li>Assurer que la r\u00e9mun\u00e9ration que vous offrez soit juste et \u00e9quitable et qu\u2019elle soit bas\u00e9e sur la fonction et les responsabilit\u00e9s.<\/li>\n<li>Et au besoin, offrir un soutien pour trouver et embaucher des gens qualifi\u00e9s et adaptables pour occuper des postes cl\u00e9s.<\/li>\n<\/ul>\n<p><strong>Combler les lacunes<\/strong><\/p>\n<p>Mener votre organisme \u00e0 travers une crise de cette ampleur puis le lancer sur la route du redressement qui suivra pourrait n\u00e9cessiter que vous obteniez de l\u2019aide pour assurer que certaines fonctions essentielles soient couvertes en cas d\u2019absence, ou encore que vous fassiez appel \u00e0 de nouvelles ressources pour r\u00e9pondre aux charges de travail accrues \u00e0 court-terme afin d\u2019\u00e9viter de surcharger votre \u00e9quipe de base. KCI a des professionnels en collecte de fonds exp\u00e9riment\u00e9s et qualifi\u00e9s \u00e0 travers le pays qui peuvent fournir une aide pratique de diverses fa\u00e7ons, y compris la recherche de donateurs potentiels, des services de gestion interm\u00e9diaires ainsi qu\u2019un soutien \u00e0 la formation de vos employ\u00e9s et de vos b\u00e9n\u00e9voles pour qu\u2019ils am\u00e9liorent leurs propres comp\u00e9tences afin d\u2019\u00eatre mieux outill\u00e9s pour engager vos donateurs.<\/p>\n<p><strong>(Re)Planifier et r\u00e9aliser une campagne<\/strong><\/p>\n<p>Enfin, s\u2019il y a un domaine qui aurait besoin d\u2019une r\u00e9invention alors que nous traversons cette pand\u00e9mie, c\u2019est celui des campagnes qui \u00e9taient en cours ou en mode planification. Les \u00e9ch\u00e9anciers, les strat\u00e9gies d\u2019identification des donateurs, la gestion des b\u00e9n\u00e9voles et possiblement l\u2019objectif lui-m\u00eame devront \u00eatre r\u00e9\u00e9valu\u00e9s et ajust\u00e9s au besoin. Une fois votre plan valid\u00e9, vous pourriez avoir besoin d\u2019un soutien pour vous redonner l\u2019impulsion qui vous permettra de r\u00e9aliser vos objectifs ou encore pour vous aider \u00e0 faire en sorte que votre \u00e9quipe et vous gardiez le cap. Avec nos 35 ann\u00e9es et plus d\u2019exp\u00e9rience \u00e0 aider les organismes caritatifs \u00e0 planifier et \u00e0 r\u00e9aliser leurs campagnes, autant en p\u00e9riode de prosp\u00e9rit\u00e9 qu\u2019en p\u00e9riode de crise, nous pouvons vous accompagner dans ce processus. Que votre campagne en soit \u00e0 ses d\u00e9buts, partiellement compl\u00e9t\u00e9e ou presque termin\u00e9e, si vous vous questionnez au sujet de l\u2019\u00e9tape suivante, nous sommes l\u00e0 pour d\u00e9finir la voie \u00e0 suivre avec vous.<\/p>\n<p><span style=\"color: #e56a54;\"><strong>\u00c0 PROPOS DE KCI<\/strong><\/span><\/p>\n<p>KCI est le chef de file des experts-conseils du secteur sans but lucratif au Canada, avec \u00e0 travers le pays des professionnels en collecte de fonds, en strat\u00e9gie, en recherche et analytique et en recrutement de cadres.<\/p>\n<p>Notre objectif premier est d\u2019inspirer et d\u2019habiliter les organismes \u00e0 recueillir des fonds, pour les aider \u00e0 r\u00e9aliser le r\u00eave d\u2019une collectivit\u00e9 meilleure et d\u2019une vie plus saine. Et \u00e0 travers nos 35 ann\u00e9es d\u2019exp\u00e9rience, nous avons aid\u00e9 des milliers d\u2019organismes \u00e0 \u00e9laborer leurs strat\u00e9gies, \u00e0 b\u00e2tir leurs \u00e9quipes et \u00e0 amasser des milliards de dollars dans les secteurs de l\u2019\u00e9ducation, de la sant\u00e9, des services sociaux, des arts et de la culture, de la religion et de l\u2019environnement.<\/p>\n<p>Pour ce faire, nous mettons rigoureusement l\u2019accent sur les valeurs et sur les gens\u2026 aussi bien les n\u00f4tres que les v\u00f4tres. Nous adh\u00e9rons avec fiert\u00e9 et de fa\u00e7on r\u00e9solue \u00e0 nos valeurs essentielles : la plus grande int\u00e9grit\u00e9 dans toutes nos actions; un engagement envers l\u2019excellence et l\u2019innovation dans tout ce que entreprenons; une ouverture aux id\u00e9es nouvelles; des relations collaboratives et respectueuses avec nos coll\u00e8gues et nos clients. Nous embauchons en fonction de ces valeurs et nous les vivons \u00e0 tous les jours.<\/p>\n<p>Et parce que nous savons que l\u2019avenir ne ressemblera pas au pass\u00e9, nous pla\u00e7ons le renforcement des capacit\u00e9s, le partage des connaissances et la cr\u00e9ation du savoir au c\u0153ur de tout ce que nous faisons. Nous osons l\u2019avenir, et nous aidons nos clients \u00e0 oser.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_code admin_label=\u00a0\u00bbSocial Media Share\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb]<div class=\"et_social_inline et_social_mobile_on et_social_inline_custom\">\n\t\t\t\t<div class=\"et_social_networks et_social_5col et_social_simple et_social_circle et_social_top et_social_no_animation et_social_outer_dark\">\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"et_social_icons_container\"><li class=\"et_social_facebook\">\n\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fkciphilanthropy.com%2Ffr%2Foser-reinventer-la-collecte-de-fonds%2F&#038;t=Oser%20r%C3%A9inventer%20la%20collecte%20de%20fonds%20%C3%A0%20l%E2%80%99%C3%A8re%20de%20la%20COVID-19\" class=\"et_social_share\" rel=\"nofollow\" data-social_name=\"facebook\" data-post_id=\"10627\" data-social_type=\"share\" data-location=\"inline\">\n\t\t\t\t\t\t\t\t\t\t<i class=\"et_social_icon et_social_icon_facebook\"><\/i><span class=\"et_social_overlay\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li><li class=\"et_social_twitter\">\n\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/twitter.com\/share?text=Oser%20r%C3%A9inventer%20la%20collecte%20de%20fonds%20%C3%A0%20l%E2%80%99%C3%A8re%20de%20la%20COVID-19&#038;url=https%3A%2F%2Fkciphilanthropy.com%2Ffr%2Foser-reinventer-la-collecte-de-fonds%2F&#038;via=kciphilanthropy\" class=\"et_social_share\" rel=\"nofollow\" data-social_name=\"twitter\" data-post_id=\"10627\" data-social_type=\"share\" data-location=\"inline\">\n\t\t\t\t\t\t\t\t\t\t<i class=\"et_social_icon et_social_icon_twitter\"><\/i><span class=\"et_social_overlay\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li><li class=\"et_social_linkedin\">\n\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fkciphilanthropy.com%2Ffr%2Foser-reinventer-la-collecte-de-fonds%2F&#038;title=Oser%20r%C3%A9inventer%20la%20collecte%20de%20fonds%20%C3%A0%20l%E2%80%99%C3%A8re%20de%20la%20COVID-19\" class=\"et_social_share\" rel=\"nofollow\" data-social_name=\"linkedin\" data-post_id=\"10627\" data-social_type=\"share\" data-location=\"inline\">\n\t\t\t\t\t\t\t\t\t\t<i class=\"et_social_icon et_social_icon_linkedin\"><\/i><span class=\"et_social_overlay\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li><li class=\"et_social_gmail\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mail.google.com\/mail\/u\/0\/?view=cm&#038;fs=1&#038;su=Oser%20r%C3%A9inventer%20la%20collecte%20de%20fonds%20%C3%A0%20l%E2%80%99%C3%A8re%20de%20la%20COVID-19&#038;body=https%3A%2F%2Fkciphilanthropy.com%2Ffr%2Foser-reinventer-la-collecte-de-fonds%2F&#038;ui=2&#038;tf=1\" class=\"et_social_share\" rel=\"nofollow\" data-social_name=\"gmail\" data-post_id=\"10627\" data-social_type=\"share\" data-location=\"inline\">\n\t\t\t\t\t\t\t\t\t\t<i class=\"et_social_icon et_social_icon_gmail\"><\/i><span class=\"et_social_overlay\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li><li class=\"et_social_printfriendly\">\n\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.printfriendly.com\/print?url=https%3A%2F%2Fkciphilanthropy.com%2Ffr%2Foser-reinventer-la-collecte-de-fonds%2F&#038;title=Oser%20r%C3%A9inventer%20la%20collecte%20de%20fonds%20%C3%A0%20l%E2%80%99%C3%A8re%20de%20la%20COVID-19\" class=\"et_social_share\" rel=\"nofollow\" data-social_name=\"printfriendly\" data-post_id=\"10627\" data-social_type=\"share\" data-location=\"inline\">\n\t\t\t\t\t\t\t\t\t\t<i class=\"et_social_icon et_social_icon_printfriendly\"><\/i><span class=\"et_social_overlay\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li><\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>[\/et_pb_code][et_pb_image src=\u00a0\u00bbhttps:\/\/kciphilanthropy.com\/wp-content\/uploads\/2020\/07\/The-Big-Rethink-Cover-Page-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbKCI &#8211; The Big Rethink &#8211; Fundraising in Era of COVID-19.pdf\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/kciphilanthropy.com\/wp-content\/uploads\/2020\/07\/KCI-The-Big-Rethink-Fundraising-in-Era-of-COVID-19.pdf\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb admin_label=\u00a0\u00bbPDF Cover\u00a0\u00bb _builder_version=\u00a0\u00bb4.5.0&Prime;][\/et_pb_image][et_pb_text admin_label=\u00a0\u00bbDownload PDF\u00a0\u00bb module_class=\u00a0\u00bbdownload-pdf\u00a0\u00bb _builder_version=\u00a0\u00bb4.5.0&Prime;]<\/p>\n<p><a href=\"https:\/\/kciphilanthropy.com\/wp-content\/uploads\/2020\/07\/KCI-The-Big-Rethink-Fundraising-in-Era-of-COVID-19.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Download PDF<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les organismes doivent faire preuve de d\u00e9termination dans la planification de leur redressement ainsi que des mesures qui les placeront sur la voie de la croissance.<\/p>\n","protected":false},"author":3,"featured_media":10623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[53],"tags":[81],"class_list":["post-10627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trends-fr","tag-tendances"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19 \/ KCI Ketchum Canada Forward Thinking<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19 \/ KCI Ketchum Canada Forward Thinking\" \/>\n<meta property=\"og:description\" content=\"Les organismes doivent faire preuve de d\u00e9termination dans la planification de leur redressement ainsi que des mesures qui les placeront sur la voie de la croissance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/\" \/>\n<meta property=\"og:site_name\" content=\"KCI Ketchum Canada Forward Thinking\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-10T15:57:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-28T13:25:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kciphilanthropy.com\/wp-content\/uploads\/2020\/07\/The-Big-Rethink-Thumbnail-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2550\" \/>\n\t<meta property=\"og:image:height\" content=\"2484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"camila\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kciphilanthropy\" \/>\n<meta name=\"twitter:site\" content=\"@kciphilanthropy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/\"},\"author\":{\"name\":\"camila\",\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/#\\\/schema\\\/person\\\/3619119cbac59ffcc4540f48de08c7b2\"},\"headline\":\"Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19\",\"datePublished\":\"2020-07-10T15:57:16+00:00\",\"dateModified\":\"2020-07-28T13:25:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/\"},\"wordCount\":4177,\"publisher\":{\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kciphilanthropy.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/The-Big-Rethink-Thumbnail-2.jpg\",\"keywords\":[\"Tendances\"],\"articleSection\":[\"Article\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/\",\"url\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/\",\"name\":\"Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19 \\\/ KCI Ketchum Canada Forward Thinking\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kciphilanthropy.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/The-Big-Rethink-Thumbnail-2.jpg\",\"datePublished\":\"2020-07-10T15:57:16+00:00\",\"dateModified\":\"2020-07-28T13:25:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kciphilanthropy.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/The-Big-Rethink-Thumbnail-2.jpg\",\"contentUrl\":\"https:\\\/\\\/kciphilanthropy.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/The-Big-Rethink-Thumbnail-2.jpg\",\"width\":2550,\"height\":2484},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/oser-reinventer-la-collecte-de-fonds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kciphilanthropy.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/#website\",\"url\":\"https:\\\/\\\/kciphilanthropy.com\\\/\",\"name\":\"KCI Ketchum Canada Forward Thinking\",\"description\":\"What&#039;s Next\",\"publisher\":{\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kciphilanthropy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/#organization\",\"name\":\"KCI What\u2019s Next.\",\"url\":\"https:\\\/\\\/kciphilanthropy.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kciphilanthropy.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/kci_logo.png\",\"contentUrl\":\"https:\\\/\\\/kciphilanthropy.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/kci_logo.png\",\"width\":227,\"height\":41,\"caption\":\"KCI What\u2019s Next.\"},\"image\":{\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/kciphilanthropy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kci-ketchum-canada\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kciphilanthropy.com\\\/#\\\/schema\\\/person\\\/3619119cbac59ffcc4540f48de08c7b2\",\"name\":\"camila\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19 \/ KCI Ketchum Canada Forward Thinking","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/","og_locale":"fr_FR","og_type":"article","og_title":"Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19 \/ KCI Ketchum Canada Forward Thinking","og_description":"Les organismes doivent faire preuve de d\u00e9termination dans la planification de leur redressement ainsi que des mesures qui les placeront sur la voie de la croissance.","og_url":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/","og_site_name":"KCI Ketchum Canada Forward Thinking","article_published_time":"2020-07-10T15:57:16+00:00","article_modified_time":"2020-07-28T13:25:40+00:00","og_image":[{"width":2550,"height":2484,"url":"https:\/\/kciphilanthropy.com\/wp-content\/uploads\/2020\/07\/The-Big-Rethink-Thumbnail-2.jpg","type":"image\/jpeg"}],"author":"camila","twitter_card":"summary_large_image","twitter_creator":"@kciphilanthropy","twitter_site":"@kciphilanthropy","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/#article","isPartOf":{"@id":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/"},"author":{"name":"camila","@id":"https:\/\/kciphilanthropy.com\/#\/schema\/person\/3619119cbac59ffcc4540f48de08c7b2"},"headline":"Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19","datePublished":"2020-07-10T15:57:16+00:00","dateModified":"2020-07-28T13:25:40+00:00","mainEntityOfPage":{"@id":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/"},"wordCount":4177,"publisher":{"@id":"https:\/\/kciphilanthropy.com\/#organization"},"image":{"@id":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/#primaryimage"},"thumbnailUrl":"https:\/\/kciphilanthropy.com\/wp-content\/uploads\/2020\/07\/The-Big-Rethink-Thumbnail-2.jpg","keywords":["Tendances"],"articleSection":["Article"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/","url":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/","name":"Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19 \/ KCI Ketchum Canada Forward Thinking","isPartOf":{"@id":"https:\/\/kciphilanthropy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/#primaryimage"},"image":{"@id":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/#primaryimage"},"thumbnailUrl":"https:\/\/kciphilanthropy.com\/wp-content\/uploads\/2020\/07\/The-Big-Rethink-Thumbnail-2.jpg","datePublished":"2020-07-10T15:57:16+00:00","dateModified":"2020-07-28T13:25:40+00:00","breadcrumb":{"@id":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/#primaryimage","url":"https:\/\/kciphilanthropy.com\/wp-content\/uploads\/2020\/07\/The-Big-Rethink-Thumbnail-2.jpg","contentUrl":"https:\/\/kciphilanthropy.com\/wp-content\/uploads\/2020\/07\/The-Big-Rethink-Thumbnail-2.jpg","width":2550,"height":2484},{"@type":"BreadcrumbList","@id":"https:\/\/kciphilanthropy.com\/fr\/oser-reinventer-la-collecte-de-fonds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kciphilanthropy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Oser r\u00e9inventer la collecte de fonds \u00e0 l\u2019\u00e8re de la COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/kciphilanthropy.com\/#website","url":"https:\/\/kciphilanthropy.com\/","name":"KCI Ketchum Canada Forward Thinking","description":"What&#039;s Next","publisher":{"@id":"https:\/\/kciphilanthropy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kciphilanthropy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kciphilanthropy.com\/#organization","name":"KCI What\u2019s Next.","url":"https:\/\/kciphilanthropy.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kciphilanthropy.com\/#\/schema\/logo\/image\/","url":"https:\/\/kciphilanthropy.com\/wp-content\/uploads\/2018\/10\/kci_logo.png","contentUrl":"https:\/\/kciphilanthropy.com\/wp-content\/uploads\/2018\/10\/kci_logo.png","width":227,"height":41,"caption":"KCI What\u2019s Next."},"image":{"@id":"https:\/\/kciphilanthropy.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/kciphilanthropy","https:\/\/www.linkedin.com\/company\/kci-ketchum-canada\/"]},{"@type":"Person","@id":"https:\/\/kciphilanthropy.com\/#\/schema\/person\/3619119cbac59ffcc4540f48de08c7b2","name":"camila"}]}},"_links":{"self":[{"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/posts\/10627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/comments?post=10627"}],"version-history":[{"count":21,"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/posts\/10627\/revisions"}],"predecessor-version":[{"id":10786,"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/posts\/10627\/revisions\/10786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/media\/10623"}],"wp:attachment":[{"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/media?parent=10627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/categories?post=10627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kciphilanthropy.com\/fr\/wp-json\/wp\/v2\/tags?post=10627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}